{"id":46830,"date":"2023-06-08T18:12:57","date_gmt":"2023-06-09T00:12:57","guid":{"rendered":"https:\/\/digitalworldpsn.com\/lego-marvel-super-heroes-2-ps4\/"},"modified":"2023-06-08T19:58:59","modified_gmt":"2023-06-09T01:58:59","slug":"lego-marvel-super-heroes-2-ps4","status":"publish","type":"product","link":"https:\/\/digitalworldpsn.com\/it\/prodotto\/lego-marvel-super-heroes-2-ps4\/","title":{"rendered":"LEGO MARVEL Super Heroes 2 PS4"},"content":{"rendered":"<p>\u00c8 tempo! Unici i tuoi supereroi e i tuoi criminali preferiti di diverse epoche e realt\u00e0 mentre affrontano il conquistatore di Kang the Conqueror nella nuova avventura originale, Lego Marvel Super Heroes 2! Gioca come i Guardiani della Galassia, Spider-Man, Thor, Hulk, Black Panther, Captain Marvel, Doctor Strange, Carnage, Green Goblin e dozzine di altri supereroi e cattivi della Marvel in questa battaglia cosmica attraverso la citt\u00e0 di Chronopolis, trasportate tempo. ! Viaggio attraverso la terra, dall&#8217;antico Egitto al vecchio West, il pianeta Hulk e New York City nel 2099 e trasporta oggetti o personaggi nel corso dei secoli! E, con nuove modalit\u00e0 di battaglia, gli amici e la famiglia possono giocare tra loro in una serie di sfide tematiche e sabbie da battaglia! -New, avventura originale, Lego Marvel Super Heroes 2. \u00b7 Viaggi attraverso la terra, dall&#8217;antico Egitto al vecchio West, il pianeta Hulk e New York nel 2099. \u00b7 Con una storia di filiale completamente originale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prezzo pi\u00f9 conveniente Consegna immediata!   Garanzia al 100% Facile installazione Oltre 300 giochi disponibili all&#8217;istante 100% originali<\/p>\n","protected":false},"featured_media":19430,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2857],"product_tag":[10639,5945,10643,7727,3734,3200,3776,5946],"class_list":{"0":"post-46830","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-giochi-digitali-per-ps4","7":"product_tag-captain-america-it","8":"product_tag-dc-it","9":"product_tag-iron-man-it","10":"product_tag-lego-it","11":"product_tag-marvel-it","12":"product_tag-shooter-it","13":"product_tag-spiderman-it","14":"product_tag-super-heroes-it","16":"first","17":"instock","18":"sale","19":"purchasable","20":"product-type-variable"},"acf":{"video":"https:\/\/www.youtube.com\/embed\/dfbqd6SF904","idiomas_soportados":"Lingue supportate <\/strong> <br Data-MCE-Fragment=1> <br Data-MCE-Fragment=1> inglese, espa\u00f1ol, italiano, fran\u00e7ais, deutsch, polski, p\u0443\u0441\u0441\u0439, Dansk, Nederlands. <\/Div>","T\u00edtulo 2":"LEGO MARVEL SUPER HEROES 2 PS4 Miglior Prezzo","Descripcion corta H3":"Scaricare\u00a0LEGO Marvel Super Heroes 2 Playstation 4 economico con garanzia"},"_links":{"self":[{"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product\/46830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/comments?post=46830"}],"version-history":[{"count":0,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product\/46830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/media\/19430"}],"wp:attachment":[{"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/media?parent=46830"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product_brand?post=46830"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product_cat?post=46830"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/digitalworldpsn.com\/it\/wp-json\/wp\/v2\/product_tag?post=46830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}